{"id":1134,"date":"2024-03-06T14:32:34","date_gmt":"2024-03-06T14:32:34","guid":{"rendered":"https:\/\/elaccs.nl\/mehr-uebersicht-mit-unserer-webapplikation\/"},"modified":"2024-03-28T10:06:58","modified_gmt":"2024-03-28T10:06:58","slug":"mehr-uebersicht-mit-unserer-webapplikation","status":"publish","type":"page","link":"https:\/\/technitrace.nl\/de\/mehr-uebersicht-mit-unserer-webapplikation\/","title":{"rendered":"Mehr \u00dcbersicht mit unserer Webapplikation"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1134\" class=\"elementor elementor-1134 elementor-513\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17f81eb e-flex e-con-boxed e-con e-parent\" data-id=\"17f81eb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb9f3e5 elementor-widget elementor-widget-spacer\" data-id=\"fb9f3e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e8909a e-flex e-con-boxed e-con e-parent\" data-id=\"5e8909a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7adfc8a e-con-full e-flex e-con e-child\" data-id=\"7adfc8a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e699438 elementor-widget elementor-widget-heading\" data-id=\"e699438\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L\u00f6sungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b01e2d elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"7b01e2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-text e--animation-none\">\n\t\t\t\t<ul id=\"menu-1-7b01e2d\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-516\"><a href=\"https:\/\/technitrace.nl\/ritregistratie\/\" class=\"elementor-item\">Fahrten\u00fcberwachung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-518\"><a href=\"https:\/\/technitrace.nl\/fleet-management\/\" class=\"elementor-item\">Flottenmanagement<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-519\"><a href=\"https:\/\/technitrace.nl\/kilometerregistratie\/\" class=\"elementor-item\">Kilometererfassung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-520\"><a href=\"https:\/\/technitrace.nl\/gps-tracker\/\" class=\"elementor-item\">GPS tracker<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-521\"><a href=\"https:\/\/technitrace.nl\/gps-volgsysteem\/\" class=\"elementor-item\">GPS Ortungssystem<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-524\"><a href=\"https:\/\/technitrace.nl\/digitale-tachograaf\/\" class=\"elementor-item\">Digitaler tachograph<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-525\"><a href=\"https:\/\/technitrace.nl\/navigatiesysteem\/\" class=\"elementor-item\">Navigationssystem<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-526\"><a href=\"https:\/\/technitrace.nl\/dieseltank-beheren\/\" class=\"elementor-item\">Dieseltank unter kontrolle<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-527\"><a href=\"https:\/\/technitrace.nl\/inzicht-met-onze-webapplicatie\/\" class=\"elementor-item\">Mehr \u00dcbersicht mit unserer Webapplikation<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-7b01e2d\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-516\"><a href=\"https:\/\/technitrace.nl\/ritregistratie\/\" class=\"elementor-item\" tabindex=\"-1\">Fahrten\u00fcberwachung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-518\"><a href=\"https:\/\/technitrace.nl\/fleet-management\/\" class=\"elementor-item\" tabindex=\"-1\">Flottenmanagement<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-519\"><a href=\"https:\/\/technitrace.nl\/kilometerregistratie\/\" class=\"elementor-item\" tabindex=\"-1\">Kilometererfassung<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-520\"><a href=\"https:\/\/technitrace.nl\/gps-tracker\/\" class=\"elementor-item\" tabindex=\"-1\">GPS tracker<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-521\"><a href=\"https:\/\/technitrace.nl\/gps-volgsysteem\/\" class=\"elementor-item\" tabindex=\"-1\">GPS Ortungssystem<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-524\"><a href=\"https:\/\/technitrace.nl\/digitale-tachograaf\/\" class=\"elementor-item\" tabindex=\"-1\">Digitaler tachograph<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-525\"><a href=\"https:\/\/technitrace.nl\/navigatiesysteem\/\" class=\"elementor-item\" tabindex=\"-1\">Navigationssystem<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-526\"><a href=\"https:\/\/technitrace.nl\/dieseltank-beheren\/\" class=\"elementor-item\" tabindex=\"-1\">Dieseltank unter kontrolle<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-527\"><a href=\"https:\/\/technitrace.nl\/inzicht-met-onze-webapplicatie\/\" class=\"elementor-item\" tabindex=\"-1\">Mehr \u00dcbersicht mit unserer Webapplikation<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd96a66 elementor-widget elementor-widget-heading\" data-id=\"fd96a66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rufen Sie an<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0076efa elementor-widget elementor-widget-text-editor\" data-id=\"0076efa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"tel:0880-513223\"><span style=\"color: #00aeef;\">0880-513223<\/span><\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e806042 elementor-widget elementor-widget-text-editor\" data-id=\"e806042\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #647992;\">oder mailen Sie uns<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8003fed elementor-widget elementor-widget-text-editor\" data-id=\"8003fed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"email\" style=\"color: #00aeef;\"><a style=\"color: #00aeef;\" href=\"mailto:info@technitrace.nl\">info@technitrace.nl<\/a><\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6ee153 elementor-widget elementor-widget-heading\" data-id=\"f6ee153\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum TechniTrace?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5f7812 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e5f7812\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Niederl\u00e4ndisches Produkt<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Niedrige Hypotheken<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Smart-Berichte<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Einfache Bedienung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Passt sich an Ihr Unternehmen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Kundenspezifische und Standard<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e70cc7 elementor-widget elementor-widget-image\" data-id=\"2e70cc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/technitrace.nl\/webapplicatie\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"239\" height=\"288\" src=\"https:\/\/technitrace.nl\/wp-content\/uploads\/2024\/03\/banner-smartphone-nl.png\" class=\"attachment-large size-large wp-image-959\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f1f8547 e-con-full e-flex e-con e-child\" data-id=\"f1f8547\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3cac6dc elementor-widget elementor-widget-text-editor\" data-id=\"3cac6dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>MEHR \u00dcBERSICHT MIT UNSERER WEBAPPLIKATION<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04baf19 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"04baf19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab8e3d2 elementor-widget elementor-widget-text-editor\" data-id=\"ab8e3d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Je effizienter Sie Ihren Fahrzeugpark einsetzen, desto mehr bleibt letztendlich unter dem Strich stehen. Kombinieren Sie Ihr Track &amp; Trace-System mit unserer praktischen Webapplikation, dann wissen Sie jederzeit wo sich Ihre Fahrzeuge befinden. So haben Sie alles jederzeit im Griff, wo immer Sie sich befinden.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89710e4 elementor-widget elementor-widget-heading\" data-id=\"89710e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">F\u00dcR SIE SELBST, MITARBEITER UND KUNDEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bec665 elementor-widget elementor-widget-text-editor\" data-id=\"0bec665\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sie selber, aber auch Ihre Mitarbeiter und Kunden k\u00f6nnen die Webapplikation benutzen. Sie entscheiden selbst, welche Angaben Anderen zug\u00e4nglich sind. Wir sorgen daf\u00fcr, dass diese Angaben auf \u00fcbersichtliche Weise angezeigt werden.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>L\u00f6sungen Rufen Sie an 0880-513223 oder mailen Sie uns info@technitrace.nl Warum TechniTrace? Niederl\u00e4ndisches Produkt Niedrige Hypotheken Smart-Berichte Einfache Bedienung Passt sich an Ihr Unternehmen Kundenspezifische und Standard MEHR \u00dcBERSICHT MIT UNSERER WEBAPPLIKATION Je effizienter Sie Ihren Fahrzeugpark einsetzen, desto mehr bleibt letztendlich unter dem Strich stehen. Kombinieren Sie Ihr Track &amp; Trace-System mit unserer praktischen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-1134","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/technitrace.nl\/de\/wp-json\/wp\/v2\/pages\/1134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/technitrace.nl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/technitrace.nl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/technitrace.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/technitrace.nl\/de\/wp-json\/wp\/v2\/comments?post=1134"}],"version-history":[{"count":5,"href":"https:\/\/technitrace.nl\/de\/wp-json\/wp\/v2\/pages\/1134\/revisions"}],"predecessor-version":[{"id":1217,"href":"https:\/\/technitrace.nl\/de\/wp-json\/wp\/v2\/pages\/1134\/revisions\/1217"}],"wp:attachment":[{"href":"https:\/\/technitrace.nl\/de\/wp-json\/wp\/v2\/media?parent=1134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}